{"id":40,"date":"2019-09-17T08:18:51","date_gmt":"2019-09-17T08:18:51","guid":{"rendered":"https:\/\/help.foosales.com\/docs\/documentation\/getting-started\/signing-up-for-the-free-trial\/"},"modified":"2026-07-22T14:02:05","modified_gmt":"2026-07-22T20:02:05","slug":"inscribirse-en-la-prueba-gratuita","status":"publish","type":"docs","link":"https:\/\/help.foosales.com\/es\/docs\/topics\/my-account\/signing-up-for-the-free-trial\/","title":{"rendered":"Inscribirse en la prueba gratuita"},"content":{"rendered":"<p>El FooSales <a href=\"https:\/\/www.foosales.com\/start\" target=\"_blank\" rel=\"noopener\">7 d\u00edas de prueba gratuita<\/a> proporciona acceso a todas las funciones de FooSales y le permite evaluar adecuadamente FooSales antes de comprometerse a un plan activo. La prueba gratuita incluye acceso en cualquier ordenador, iPad o tableta Android y no requiere datos de tarjeta de cr\u00e9dito. Puede elegir un plan de pago durante su prueba gratuita o esperar hasta el final de su periodo de prueba gratuita. La prueba gratuita comienza cuando te registras, no cuando empiezas a utilizar FooSales.<\/p>\n<p><strong><a href=\"https:\/\/www.foosales.com\/signup\" target=\"_blank\" rel=\"noopener\">Reg\u00edstrate para una prueba gratuita de 7 d\u00edas \u2192<\/a><\/strong><\/p>\n<p>Despu\u00e9s de suscribirse a la versi\u00f3n de prueba gratuita, deber\u00e1 instalar la aplicaci\u00f3n <a href=\"https:\/\/help.foosales.com\/es\/docs\/temas\/como-empezar\/installing-the-foosales-plugin\/\">Plugin FooSales WordPress<\/a>.<\/p>\n<p>Si no <a href=\"https:\/\/www.foosales.com\/pricing\/\" target=\"_blank\" rel=\"noopener\">seleccione un plan FooSales<\/a> al final de la prueba gratuita, tu cuenta se pondr\u00e1 en pausa y no podr\u00e1s seguir utilizando las aplicaciones FooSales hasta que adquieras un plan de pago. Si no eliges un plan de precios durante la prueba gratuita, no es necesario que realices ninguna acci\u00f3n para cancelar tu cuenta FooSales.<\/p>","protected":false},"featured_media":0,"parent":23,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_is_vendor_doc":"0","footnotes":""},"doc_tag":[3,31],"class_list":["post-40","docs","type-docs","status-publish","hentry","doc_tag-free-trial","doc_tag-sign-up"],"comment_count":0,"_links":{"self":[{"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"replies":[{"embeddable":true,"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/comments?post=40"}],"version-history":[{"count":4,"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs\/40\/revisions"}],"predecessor-version":[{"id":56306,"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs\/40\/revisions\/56306"}],"up":[{"embeddable":true,"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs\/23"}],"next":[{"title":"Vincula tu tienda o tiendas a FooSales","link":"https:\/\/help.foosales.com\/es\/docs\/topics\/my-account\/linking-your-store-to-foosales\/","href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/docs\/49"}],"wp:attachment":[{"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/help.foosales.com\/es\/wp-json\/wp\/v2\/doc_tag?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}